{"id":201,"date":"2021-11-15T16:09:39","date_gmt":"2021-11-15T15:09:39","guid":{"rendered":"https:\/\/www.matthieueverst.com\/ME_blog\/?p=201"},"modified":"2021-11-15T16:29:06","modified_gmt":"2021-11-15T15:29:06","slug":"larbre-de-vie","status":"publish","type":"post","link":"https:\/\/www.matthieueverst.com\/ME_blog\/larbre-de-vie\/","title":{"rendered":"L&#8217;Arbre de Vie"},"content":{"rendered":"\n<div class=\"wp-block-image\"><figure class=\"aligncenter size-large is-resized\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.matthieueverst.com\/ME_blog\/wp-content\/uploads\/2021\/11\/couverture-figue-3-853x1024.png\" alt=\"image en r\u00e9f\u00e9rence \u00e0 l'Arbre de Vie\" class=\"wp-image-210\" width=\"308\" height=\"369\" srcset=\"https:\/\/www.matthieueverst.com\/ME_blog\/wp-content\/uploads\/2021\/11\/couverture-figue-3-853x1024.png 853w, https:\/\/www.matthieueverst.com\/ME_blog\/wp-content\/uploads\/2021\/11\/couverture-figue-3-250x300.png 250w\" sizes=\"auto, (max-width: 308px) 85vw, 308px\" \/><figcaption>L&#8217;Arbre de Vie \/ L&#8217;Arbre de la Connaissance du Bien et du Mal<\/figcaption><\/figure><\/div>\n\n\n\n<p class=\"wp-block-paragraph\">L\u2019\u00e9criture comme moyen pour se souvenir ou \u00e0 l\u2019inverse comme processus pour se rappeler. Figer des pens\u00e9es pour le futur ou ramener \u00e0 sa conscience des images du pass\u00e9\u2026<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">C\u2019est au cours de ma progression dans l\u2019\u00e9criture du <a href=\"https:\/\/www.matthieueverst.com\/lecontedundeluge.html\" target=\"_blank\" rel=\"noreferrer noopener\">court essai<\/a> que j\u2019avais en t\u00eate depuis plusieurs ann\u00e9es, qu\u2019une question rest\u00e9e en suspens depuis mon enfance ressurgit. Cette question avait fini par se fondre dans le paysage au milieu de l\u2019accumulation croissante des images qui s\u2019additionneraient au cours du temps pour le constituer. La maille d\u2019une trame, le n\u0153ud d\u2019un filet, un point de l\u2019horizon. Enlevez-le et il vous r\u00e9v\u00e8lera un trou visible aux d\u00e9pens de tout le reste, mais laissez-le en place et il s\u2019effacera derri\u00e8re l\u2019int\u00e9grit\u00e9 de l\u2019ensemble. Rien qu\u2019un point, au loin, que rien ne distingue du fond jusqu\u2019\u00e0 ce qu\u2019il vous soit point\u00e9 du doigt pour devenir l\u2019objet central de votre attention.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Ce point \u00e9tait un arbre et pas n\u2019importe lequel. L\u2019arbre le plus important de notre humanit\u00e9, celui qui occupe la place centrale de l\u2019un des deux r\u00e9cits de la cr\u00e9ation figurant dans la Gen\u00e8se&nbsp;: l\u2019Arbre de Vie.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">L\u2019Arbre de la connaissance du bien et du mal me paraissait plus familier par le r\u00f4le central qu\u2019il occupe dans le r\u00e9cit avec son fruit tentateur. Mais l\u2019Arbre de Vie qui est mentionn\u00e9 au tout d\u00e9but du r\u00e9cit, qu\u2019est-il, et surtout s\u2019efface-t-il vraiment dans le corps du r\u00e9cit&nbsp;?<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Tant\u00f4t en opposition directe avec l\u2019Arbre de la connaissance du bien et du mal, tant\u00f4t confondu avec lui quand \u00c8ve d\u00e9signe ce dernier comme plant\u00e9 lui-aussi au centre du jardin.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Salomon, l\u2019homme qui voulait \u00e9pouser la sagesse, savait bien que pour celui qui parviendrait \u00e0 la tenir, elle deviendrait arbre de vie. C\u2019est ainsi qu\u2019il d\u00e9finit la sagesse dans les <a href=\"https:\/\/www.aelf.org\/bible\/Pr\/1\" target=\"_blank\" rel=\"noreferrer noopener\">Proverbes<\/a> <sup>[Pr 3,18]<\/sup> des Livres Po\u00e9tiques et Sapientiaux. Mais voil\u00e0, la sagesse ne s\u2019acqui\u00e8re pas du jour au lendemain&nbsp;: on ne peut la donner, on ne peut que la trouver en soi. C\u2019est un chemin personnel, une exp\u00e9rience propre au temps, \u00e0 l\u2019oppos\u00e9 m\u00eame d\u2019une information que l\u2019on communique instantan\u00e9ment et qui est prise par tous, m\u00eame ceux qui ne sont pas pr\u00eats pour la recevoir.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Une sagesse au service de tous, universelle et porteuse de vie, contre une connaissance du bien et du mal, donn\u00e9es subjectives et ainsi source de conflits. Cueillir le fruit revenait \u00e0 s\u2019accaparer la connaissance puisqu\u2019un autre s\u2019en trouvait in\u00e9vitablement priv\u00e9, rendant de fait cette m\u00eame connaissance st\u00e9rile.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Et voil\u00e0 que je prends la pleine mesure de cette conclusion d\u2019<a href=\"https:\/\/henrigougaud.com\/\" target=\"_blank\" rel=\"noreferrer noopener\">Henri Gougaud<\/a>&nbsp;: ce n\u2019est pas pour que l\u2019on cueille son fruit que l\u2019arbre a \u00e9t\u00e9 mis au centre du jardin, mais pour qu\u2019il nous inspire \u00e0 devenir comme lui et \u00e0 porter \u00e0 notre tour du fruit\u2026<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La connaissance et la sagesse comme les deux faces d\u2019une m\u00eame pi\u00e8ce&nbsp;: un seul et m\u00eame arbre mais deux chemins.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Finalement peut-\u00eatre me fallait-il simplement du temps, le temps de laisser l\u2019id\u00e9e murir afin qu\u2019elle apporte d\u2019elle-m\u00eame par l\u2019exp\u00e9rience une r\u00e9ponse \u00e0 cette question. Une r\u00e9ponse plut\u00f4t qu\u2019une donn\u00e9e.<\/p>\n\n\n","protected":false},"excerpt":{"rendered":"<p>L\u2019\u00e9criture comme moyen pour se souvenir ou \u00e0 l\u2019inverse comme processus pour se rappeler. Figer des pens\u00e9es pour le futur ou ramener \u00e0 sa conscience des images du pass\u00e9\u2026 C\u2019est au cours de ma progression dans l\u2019\u00e9criture du court essai que j\u2019avais en t\u00eate depuis plusieurs ann\u00e9es, qu\u2019une question rest\u00e9e en suspens depuis mon enfance &hellip; <a href=\"https:\/\/www.matthieueverst.com\/ME_blog\/larbre-de-vie\/\" class=\"more-link\">Continuer la lecture<span class=\"screen-reader-text\"> de &laquo;&nbsp;L&#8217;Arbre de Vie&nbsp;&raquo;<\/span><\/a><\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[43],"tags":[58,62,49,61,35,60,66,36,63,59],"class_list":["post-201","post","type-post","status-publish","format-standard","hentry","category-extraits","tag-arbre-de-vie","tag-connaissance-du-bien-et-du-mal","tag-conte","tag-deluge","tag-eden","tag-genese","tag-henri-gougaud","tag-jardin","tag-recit-de-la-creation","tag-sagesse"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>L&#039;Arbre de Vie - Blog de Matthieu EVERST<\/title>\n<meta name=\"description\" content=\"Ce point dans l&#039;horizon \u00e9tait un arbre et pas n\u2019importe lequel, le plus important de notre humanit\u00e9 : l\u2019Arbre de Vie.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.matthieueverst.com\/ME_blog\/larbre-de-vie\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"L&#039;Arbre de Vie - Blog de Matthieu EVERST\" \/>\n<meta property=\"og:description\" content=\"Ce point dans l&#039;horizon \u00e9tait un arbre et pas n\u2019importe lequel, le plus important de notre humanit\u00e9 : l\u2019Arbre de Vie.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.matthieueverst.com\/ME_blog\/larbre-de-vie\/\" \/>\n<meta property=\"og:site_name\" content=\"Blog de Matthieu EVERST\" \/>\n<meta property=\"article:published_time\" content=\"2021-11-15T15:09:39+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2021-11-15T15:29:06+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.matthieueverst.com\/ME_blog\/wp-content\/uploads\/2021\/11\/couverture-figue-3-853x1024.png\" \/>\n<meta name=\"author\" content=\"ME\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"ME\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.matthieueverst.com\\\/ME_blog\\\/larbre-de-vie\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.matthieueverst.com\\\/ME_blog\\\/larbre-de-vie\\\/\"},\"author\":{\"name\":\"ME\",\"@id\":\"https:\\\/\\\/www.matthieueverst.com\\\/ME_blog\\\/#\\\/schema\\\/person\\\/8fe08c371cc1d926802da14c40c98ba8\"},\"headline\":\"L&#8217;Arbre de Vie\",\"datePublished\":\"2021-11-15T15:09:39+00:00\",\"dateModified\":\"2021-11-15T15:29:06+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.matthieueverst.com\\\/ME_blog\\\/larbre-de-vie\\\/\"},\"wordCount\":603,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/www.matthieueverst.com\\\/ME_blog\\\/#\\\/schema\\\/person\\\/8fe08c371cc1d926802da14c40c98ba8\"},\"image\":{\"@id\":\"https:\\\/\\\/www.matthieueverst.com\\\/ME_blog\\\/larbre-de-vie\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.matthieueverst.com\\\/ME_blog\\\/wp-content\\\/uploads\\\/2021\\\/11\\\/couverture-figue-3-853x1024.png\",\"keywords\":[\"arbre de vie\",\"connaissance du bien et du mal\",\"conte\",\"d\u00e9luge\",\"Eden\",\"gen\u00e8se\",\"henri gougaud\",\"Jardin\",\"r\u00e9cit de la cr\u00e9ation\",\"sagesse\"],\"articleSection\":[\"Extraits\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.matthieueverst.com\\\/ME_blog\\\/larbre-de-vie\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.matthieueverst.com\\\/ME_blog\\\/larbre-de-vie\\\/\",\"url\":\"https:\\\/\\\/www.matthieueverst.com\\\/ME_blog\\\/larbre-de-vie\\\/\",\"name\":\"L'Arbre de Vie - Blog de Matthieu EVERST\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.matthieueverst.com\\\/ME_blog\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.matthieueverst.com\\\/ME_blog\\\/larbre-de-vie\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.matthieueverst.com\\\/ME_blog\\\/larbre-de-vie\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.matthieueverst.com\\\/ME_blog\\\/wp-content\\\/uploads\\\/2021\\\/11\\\/couverture-figue-3-853x1024.png\",\"datePublished\":\"2021-11-15T15:09:39+00:00\",\"dateModified\":\"2021-11-15T15:29:06+00:00\",\"description\":\"Ce point dans l'horizon \u00e9tait un arbre et pas n\u2019importe lequel, le plus important de notre humanit\u00e9 : l\u2019Arbre de Vie.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.matthieueverst.com\\\/ME_blog\\\/larbre-de-vie\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.matthieueverst.com\\\/ME_blog\\\/larbre-de-vie\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.matthieueverst.com\\\/ME_blog\\\/larbre-de-vie\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.matthieueverst.com\\\/ME_blog\\\/wp-content\\\/uploads\\\/2021\\\/11\\\/couverture-figue-3.png\",\"contentUrl\":\"https:\\\/\\\/www.matthieueverst.com\\\/ME_blog\\\/wp-content\\\/uploads\\\/2021\\\/11\\\/couverture-figue-3.png\",\"width\":3000,\"height\":3600,\"caption\":\"L'Arbre de Vie \\\/ L'Arbre de la Connaissance du Bien et du Mal\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.matthieueverst.com\\\/ME_blog\\\/larbre-de-vie\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/www.matthieueverst.com\\\/ME_blog\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"L&#8217;Arbre de Vie\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.matthieueverst.com\\\/ME_blog\\\/#website\",\"url\":\"https:\\\/\\\/www.matthieueverst.com\\\/ME_blog\\\/\",\"name\":\"Blog de Matthieu EVERST\",\"description\":\"Des articles sur le th\u00e8me du Temps\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.matthieueverst.com\\\/ME_blog\\\/#\\\/schema\\\/person\\\/8fe08c371cc1d926802da14c40c98ba8\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.matthieueverst.com\\\/ME_blog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":[\"Person\",\"Organization\"],\"@id\":\"https:\\\/\\\/www.matthieueverst.com\\\/ME_blog\\\/#\\\/schema\\\/person\\\/8fe08c371cc1d926802da14c40c98ba8\",\"name\":\"ME\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/0291fc5a9cb7e5015a900b221f5755371a4f2665e53625eed4f498f4c80bfb8f?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/0291fc5a9cb7e5015a900b221f5755371a4f2665e53625eed4f498f4c80bfb8f?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/0291fc5a9cb7e5015a900b221f5755371a4f2665e53625eed4f498f4c80bfb8f?s=96&d=mm&r=g\",\"caption\":\"ME\"},\"logo\":{\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/0291fc5a9cb7e5015a900b221f5755371a4f2665e53625eed4f498f4c80bfb8f?s=96&d=mm&r=g\"},\"description\":\"Matthieu EVERST est chercheur en physique et passionn\u00e9 par les civilisations anciennes. Il s\u2019int\u00e9resse notamment \u00e0 la \u00ab pierre \u00bb, support par lequel ces premi\u00e8res soci\u00e9t\u00e9s nous ont laiss\u00e9 le t\u00e9moignage de leur pr\u00e9sence et un instantan\u00e9 de leur rapport au monde. Il est l\u2019auteur du roman intitul\u00e9 \u00ab Si j\u2019avais le Temps\u2026 \u00bb dans lequel le personnage principal plonge au c\u0153ur de la nature du Temps \u00e0 travers un cheminement int\u00e9rieur qui le conduira jusqu\u2019\u00e0 Stonehenge.\",\"sameAs\":[\"https:\\\/\\\/www.matthieueverst.com\\\/ME_blog\",\"https:\\\/\\\/www.instagram.com\\\/matthieueverst\\\/\"],\"url\":\"https:\\\/\\\/www.matthieueverst.com\\\/ME_blog\\\/author\\\/me\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"L'Arbre de Vie - Blog de Matthieu EVERST","description":"Ce point dans l'horizon \u00e9tait un arbre et pas n\u2019importe lequel, le plus important de notre humanit\u00e9 : l\u2019Arbre de Vie.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.matthieueverst.com\/ME_blog\/larbre-de-vie\/","og_locale":"fr_FR","og_type":"article","og_title":"L'Arbre de Vie - Blog de Matthieu EVERST","og_description":"Ce point dans l'horizon \u00e9tait un arbre et pas n\u2019importe lequel, le plus important de notre humanit\u00e9 : l\u2019Arbre de Vie.","og_url":"https:\/\/www.matthieueverst.com\/ME_blog\/larbre-de-vie\/","og_site_name":"Blog de Matthieu EVERST","article_published_time":"2021-11-15T15:09:39+00:00","article_modified_time":"2021-11-15T15:29:06+00:00","og_image":[{"url":"https:\/\/www.matthieueverst.com\/ME_blog\/wp-content\/uploads\/2021\/11\/couverture-figue-3-853x1024.png","type":"","width":"","height":""}],"author":"ME","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"ME","Dur\u00e9e de lecture estim\u00e9e":"3 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.matthieueverst.com\/ME_blog\/larbre-de-vie\/#article","isPartOf":{"@id":"https:\/\/www.matthieueverst.com\/ME_blog\/larbre-de-vie\/"},"author":{"name":"ME","@id":"https:\/\/www.matthieueverst.com\/ME_blog\/#\/schema\/person\/8fe08c371cc1d926802da14c40c98ba8"},"headline":"L&#8217;Arbre de Vie","datePublished":"2021-11-15T15:09:39+00:00","dateModified":"2021-11-15T15:29:06+00:00","mainEntityOfPage":{"@id":"https:\/\/www.matthieueverst.com\/ME_blog\/larbre-de-vie\/"},"wordCount":603,"commentCount":0,"publisher":{"@id":"https:\/\/www.matthieueverst.com\/ME_blog\/#\/schema\/person\/8fe08c371cc1d926802da14c40c98ba8"},"image":{"@id":"https:\/\/www.matthieueverst.com\/ME_blog\/larbre-de-vie\/#primaryimage"},"thumbnailUrl":"https:\/\/www.matthieueverst.com\/ME_blog\/wp-content\/uploads\/2021\/11\/couverture-figue-3-853x1024.png","keywords":["arbre de vie","connaissance du bien et du mal","conte","d\u00e9luge","Eden","gen\u00e8se","henri gougaud","Jardin","r\u00e9cit de la cr\u00e9ation","sagesse"],"articleSection":["Extraits"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.matthieueverst.com\/ME_blog\/larbre-de-vie\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.matthieueverst.com\/ME_blog\/larbre-de-vie\/","url":"https:\/\/www.matthieueverst.com\/ME_blog\/larbre-de-vie\/","name":"L'Arbre de Vie - Blog de Matthieu EVERST","isPartOf":{"@id":"https:\/\/www.matthieueverst.com\/ME_blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.matthieueverst.com\/ME_blog\/larbre-de-vie\/#primaryimage"},"image":{"@id":"https:\/\/www.matthieueverst.com\/ME_blog\/larbre-de-vie\/#primaryimage"},"thumbnailUrl":"https:\/\/www.matthieueverst.com\/ME_blog\/wp-content\/uploads\/2021\/11\/couverture-figue-3-853x1024.png","datePublished":"2021-11-15T15:09:39+00:00","dateModified":"2021-11-15T15:29:06+00:00","description":"Ce point dans l'horizon \u00e9tait un arbre et pas n\u2019importe lequel, le plus important de notre humanit\u00e9 : l\u2019Arbre de Vie.","breadcrumb":{"@id":"https:\/\/www.matthieueverst.com\/ME_blog\/larbre-de-vie\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.matthieueverst.com\/ME_blog\/larbre-de-vie\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.matthieueverst.com\/ME_blog\/larbre-de-vie\/#primaryimage","url":"https:\/\/www.matthieueverst.com\/ME_blog\/wp-content\/uploads\/2021\/11\/couverture-figue-3.png","contentUrl":"https:\/\/www.matthieueverst.com\/ME_blog\/wp-content\/uploads\/2021\/11\/couverture-figue-3.png","width":3000,"height":3600,"caption":"L'Arbre de Vie \/ L'Arbre de la Connaissance du Bien et du Mal"},{"@type":"BreadcrumbList","@id":"https:\/\/www.matthieueverst.com\/ME_blog\/larbre-de-vie\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/www.matthieueverst.com\/ME_blog\/"},{"@type":"ListItem","position":2,"name":"L&#8217;Arbre de Vie"}]},{"@type":"WebSite","@id":"https:\/\/www.matthieueverst.com\/ME_blog\/#website","url":"https:\/\/www.matthieueverst.com\/ME_blog\/","name":"Blog de Matthieu EVERST","description":"Des articles sur le th\u00e8me du Temps","publisher":{"@id":"https:\/\/www.matthieueverst.com\/ME_blog\/#\/schema\/person\/8fe08c371cc1d926802da14c40c98ba8"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.matthieueverst.com\/ME_blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":["Person","Organization"],"@id":"https:\/\/www.matthieueverst.com\/ME_blog\/#\/schema\/person\/8fe08c371cc1d926802da14c40c98ba8","name":"ME","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/secure.gravatar.com\/avatar\/0291fc5a9cb7e5015a900b221f5755371a4f2665e53625eed4f498f4c80bfb8f?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/0291fc5a9cb7e5015a900b221f5755371a4f2665e53625eed4f498f4c80bfb8f?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/0291fc5a9cb7e5015a900b221f5755371a4f2665e53625eed4f498f4c80bfb8f?s=96&d=mm&r=g","caption":"ME"},"logo":{"@id":"https:\/\/secure.gravatar.com\/avatar\/0291fc5a9cb7e5015a900b221f5755371a4f2665e53625eed4f498f4c80bfb8f?s=96&d=mm&r=g"},"description":"Matthieu EVERST est chercheur en physique et passionn\u00e9 par les civilisations anciennes. Il s\u2019int\u00e9resse notamment \u00e0 la \u00ab pierre \u00bb, support par lequel ces premi\u00e8res soci\u00e9t\u00e9s nous ont laiss\u00e9 le t\u00e9moignage de leur pr\u00e9sence et un instantan\u00e9 de leur rapport au monde. Il est l\u2019auteur du roman intitul\u00e9 \u00ab Si j\u2019avais le Temps\u2026 \u00bb dans lequel le personnage principal plonge au c\u0153ur de la nature du Temps \u00e0 travers un cheminement int\u00e9rieur qui le conduira jusqu\u2019\u00e0 Stonehenge.","sameAs":["https:\/\/www.matthieueverst.com\/ME_blog","https:\/\/www.instagram.com\/matthieueverst\/"],"url":"https:\/\/www.matthieueverst.com\/ME_blog\/author\/me\/"}]}},"_links":{"self":[{"href":"https:\/\/www.matthieueverst.com\/ME_blog\/wp-json\/wp\/v2\/posts\/201","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.matthieueverst.com\/ME_blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.matthieueverst.com\/ME_blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.matthieueverst.com\/ME_blog\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.matthieueverst.com\/ME_blog\/wp-json\/wp\/v2\/comments?post=201"}],"version-history":[{"count":3,"href":"https:\/\/www.matthieueverst.com\/ME_blog\/wp-json\/wp\/v2\/posts\/201\/revisions"}],"predecessor-version":[{"id":212,"href":"https:\/\/www.matthieueverst.com\/ME_blog\/wp-json\/wp\/v2\/posts\/201\/revisions\/212"}],"wp:attachment":[{"href":"https:\/\/www.matthieueverst.com\/ME_blog\/wp-json\/wp\/v2\/media?parent=201"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.matthieueverst.com\/ME_blog\/wp-json\/wp\/v2\/categories?post=201"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.matthieueverst.com\/ME_blog\/wp-json\/wp\/v2\/tags?post=201"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}